{"id":5730,"date":"2020-11-07T22:27:44","date_gmt":"2020-11-07T21:27:44","guid":{"rendered":"https:\/\/solidaires-etudiant-e-s.org\/archive\/\/?p=5730"},"modified":"2020-11-07T22:27:44","modified_gmt":"2020-11-07T21:27:44","slug":"communique-un-an-apres-la-precarite-etudiante-tue-toujours","status":"publish","type":"post","link":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/","title":{"rendered":"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours !"},"content":{"rendered":"\n<p>Il y a un an, notre camarade Anas s\u2019est immol\u00e9 devant le CROUS de Lyon. Par un message publi\u00e9 sur Facebook avant son passage \u00e0 l\u2019acte, il en a affirm\u00e9 tout le sens politique : \u00e0 bout face \u00e0 la pr\u00e9carit\u00e9 qu\u2019il subissait en tant qu\u2019\u00e9tudiant, apr\u00e8s un refus de bourse du fait d\u2019un redoublement de trop, il a voulu visibiliser la situation de d\u00e9tresse dans laquelle se trouvaient et continuent de se trouver de nombreux et nombreuses \u00e9tudiant-es.<\/p>\n\n\n<p>Suite \u00e0 son geste,<strong> une forte mobilisation contre la pr\u00e9carit\u00e9 \u00e9tudiante \u00e0 \u00e9merg\u00e9 partout en France dont un rassemblement unitaire le 12 novembre 2019.<\/strong><br \/>Depuis plus d\u2019un an, nous n\u2019avons cess\u00e9 de d\u00e9noncer les conditions de pr\u00e9carit\u00e9 massive des \u00e9tudiant-es et tent\u00e9 de les rendre visible dans le d\u00e9bat public. Nous voulons aujourd\u2019hui, encore une fois, en rappeler les chiffres inqui\u00e9tants. D\u2019apr\u00e8s l\u2019Observatoire de la Vie \u00c9tudiante dans son rapport de 2016, 30% des \u00e9tudiant-es ne sont pas aid\u00e9-es par leurs parents et la moiti\u00e9 sont contraint-es de travailler en parall\u00e8le de leurs \u00e9tudes. Avec un \u00e9chelon maximal de bourse (report\u00e9 sur 12 mois) d\u2019environ 452\u20ac et une moyenne des loyers de 430\u20ac, nous sommes oblig\u00e9-es de faire l\u2019impasse sur d\u2019autres d\u00e9penses. Ainsi, selon une \u00e9tude de la MGEN1 de 2019, 43% des \u00e9tudiant-es renoncent aux soins dont au moins la moiti\u00e9 par manque d\u2019argent. De plus, selon une \u00e9tude de la FAGE2 de 2017, 65% des \u00e9tudiant-e-s sautent r\u00e9guli\u00e8rement un repas faute d\u2019argent.<\/p>\n\n\n<p>Suite \u00e0 la mobilisation des \u00e9tudiant-es, le gouvernement a annonc\u00e9 deux mesures : la mise en place d\u2019un num\u00e9ro vert et des repas \u00e0 1\u20ac dans tous les Resto U pour les \u00e9tudiant-es boursi\u00e8r-es. La pr\u00e9carit\u00e9 \u00e9tudiante est un sujet s\u00e9rieux et urgent qui m\u00e9rite mieux que ce que qui a \u00e9t\u00e9 \u00e0 nos yeux un pansement sur une jambe de bois. Alors que l\u2019\u00e9pid\u00e9mie de Covid-19 et les mesures sanitaires aggravent la condition de pr\u00e9carit\u00e9 de nombreux-ses \u00e9tudiant-es notamment en les privant des emplois, souvent non d\u00e9clar\u00e9s, qui assurent leur survie. <strong>Il est plus que temps pour les pouvoirs publics de mettre un terme \u00e0 leur inaction caract\u00e9ris\u00e9e.<\/strong><br \/>Comment peut-on accepter que les r\u00e9sidences CROUS ne puissent accueillir que 6% de la population \u00e9tudiante ? Quid de l\u2019acc\u00e8s aux soins dans les services de m\u00e9decine pr\u00e9ventive des universit\u00e9s, sous-dot\u00e9s en personnel et budget ?<\/p>\n\n\n<p>Nous exigeons notamment :<\/p>\n\n\n<ul class=\"wp-block-list\"><li>Le respect de la tr\u00eave hivernale dans les r\u00e9sidences CROUS ainsi que la transformation des droits d\u2019occupations actuels, pr\u00e9caires, en baux de droit commun.<\/li><li>L\u2019augmentation d\u2019au moins 20% du montant des bourses \u00e9tudiantes ainsi que l\u2019\u00e9largissement de leurs crit\u00e8res d\u2019acc\u00e8s<\/li><li>Le gel du ticket du Restaurant Universitaire (RU) et la prise en charge par l\u2019\u00e9tat \u00e0 plus de 50 % du co\u00fbt du ticket.<\/li><li>Le renforcement massif des services de sant\u00e9 (physique et psychique) universitaires en termes de moyens, de personnel et de publicisation.<\/li><\/ul>\n\n\n<p>Vous pourrez retrouver notre cahier de revendications <a href=\"https:\/\/solidaires-etudiant.org\/site\/wp-content\/uploads\/2020\/09\/Cahier-des-revendications-precarite-Solidaires-Etudiant.e.s.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">sur ce lien<\/a>.<\/p>\n\n\n<h5 class=\"has-text-align-center wp-block-heading\"><strong>Face aux r\u00e9formes d\u2019aust\u00e9rit\u00e9 mises en place et au milieu d\u2019un reconfinement d\u00e9gradant nos conditions mat\u00e9rielles d\u2019existence, il est aujourd\u2019hui plus que n\u00e9cessaire que nous nous organisions collectivement :<br \/>Contre la pr\u00e9carit\u00e9 \u00e9tudiante et pour l\u2019am\u00e9lioration de nos conditions d\u2019\u00e9tudes, syndiquons-nous !<\/strong><\/h5>\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/solidaires-etudiant.org\/site\/wp-content\/uploads\/2020\/11\/Un-an-apres-la-precarite-etudiante-tue-toujours.pdf\">Le communiqu\u00e9 en PDF<\/a><a href=\"https:\/\/solidaires-etudiant.org\/site\/wp-content\/uploads\/2020\/11\/Un-an-apres-la-precarite-etudiante-tue-toujours.pdf\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il y a un an, notre camarade Anas s\u2019est immol\u00e9 devant le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-5730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques","col-md-12"],"featured_image_src":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg","author_info":{"display_name":"Solidaires \u00e9tudiant-e-s","author_link":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours ! - Solidaires \u00e9tudiant-e-s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours ! - Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"og:description\" content=\"Il y a un an, notre camarade Anas s\u2019est immol\u00e9 devant le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/\" \/>\n<meta property=\"og:site_name\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-07T21:27:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"999\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:site\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/\"},\"author\":{\"name\":\"Solidaires \u00e9tudiant-e-s\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\"},\"headline\":\"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours !\",\"datePublished\":\"2020-11-07T21:27:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/\"},\"wordCount\":588,\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/etudiants-precaires2.jpg\",\"articleSection\":[\"COMMUNIQUES NATIONAUX\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/\",\"name\":\"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours ! - Solidaires \u00e9tudiant-e-s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/etudiants-precaires2.jpg\",\"datePublished\":\"2020-11-07T21:27:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/etudiants-precaires2.jpg\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/etudiants-precaires2.jpg\",\"width\":999,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2020\\\/11\\\/07\\\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"description\":\"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !\",\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"width\":1181,\"height\":827,\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/solidaires-etudiant-e-s.org\",\"https:\\\/\\\/mastodon.social\\\/@solidairesetu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_iZN9gmVAAnXbBM7wAWOag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"sameAs\":[\"https:\\\/\\\/solidaires-etudiant.org\\\/site\",\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Solidaires_tudiant-e-s\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours ! - Solidaires \u00e9tudiant-e-s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/","og_locale":"fr_FR","og_type":"article","og_title":"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours ! - Solidaires \u00e9tudiant-e-s","og_description":"Il y a un an, notre camarade Anas s\u2019est immol\u00e9 devant le [&hellip;]","og_url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/","og_site_name":"Solidaires \u00e9tudiant-e-s","article_publisher":"https:\/\/www.facebook.com\/solidairesetudiantes","article_author":"https:\/\/www.facebook.com\/solidairesetudiantes","article_published_time":"2020-11-07T21:27:44+00:00","og_image":[{"width":999,"height":487,"url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg","type":"image\/jpeg"}],"author":"Solidaires \u00e9tudiant-e-s","twitter_card":"summary_large_image","twitter_creator":"@SolidairesEtu","twitter_site":"@SolidairesEtu","twitter_misc":{"\u00c9crit par":"Solidaires \u00e9tudiant-e-s","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#article","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/"},"author":{"name":"Solidaires \u00e9tudiant-e-s","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c"},"headline":"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours !","datePublished":"2020-11-07T21:27:44+00:00","mainEntityOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/"},"wordCount":588,"publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg","articleSection":["COMMUNIQUES NATIONAUX"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/","name":"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours ! - Solidaires \u00e9tudiant-e-s","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#primaryimage"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg","datePublished":"2020-11-07T21:27:44+00:00","breadcrumb":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#primaryimage","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/11\/etudiants-precaires2.jpg","width":999,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2020\/11\/07\/communique-un-an-apres-la-precarite-etudiante-tue-toujours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/solidaires-etudiant-e-s.org\/site\/"},{"@type":"ListItem","position":2,"name":"[Communiqu\u00e9] Un an apr\u00e8s, la pr\u00e9carit\u00e9 \u00e9tudiante tue toujours !"}]},{"@type":"WebSite","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","name":"Solidaires \u00e9tudiant-e-s","description":"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !","publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidaires-etudiant-e-s.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization","name":"Solidaires \u00e9tudiant-e-s","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","width":1181,"height":827,"caption":"Solidaires \u00e9tudiant-e-s"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/x.com\/SolidairesEtu","https:\/\/www.instagram.com\/solidairesetu\/","https:\/\/bsky.app\/profile\/solidaires-etudiant-e-s.org","https:\/\/mastodon.social\/@solidairesetu","https:\/\/www.youtube.com\/channel\/UC_iZN9gmVAAnXbBM7wAWOag"]},{"@type":"Person","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c","name":"Solidaires \u00e9tudiant-e-s","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","caption":"Solidaires \u00e9tudiant-e-s"},"sameAs":["https:\/\/solidaires-etudiant.org\/site","https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/www.instagram.com\/solidairesetu","https:\/\/x.com\/SolidairesEtu","https:\/\/fr.wikipedia.org\/wiki\/Solidaires_tudiant-e-s"]}]}},"_links":{"self":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/5730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/comments?post=5730"}],"version-history":[{"count":0,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/5730\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media\/5733"}],"wp:attachment":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media?parent=5730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories?post=5730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/tags?post=5730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}