{"id":3916,"date":"2017-09-06T08:27:06","date_gmt":"2017-09-06T06:27:06","guid":{"rendered":"http:\/\/www.solidaires-etudiant.org\/?p=3916"},"modified":"2017-09-06T08:27:06","modified_gmt":"2017-09-06T06:27:06","slug":"macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit","status":"publish","type":"post","link":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/","title":{"rendered":"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit !"},"content":{"rendered":"<p>M\u00eame si cela n&rsquo;est pas une surprise au vu du programme et des orientations politiques affich\u00e9es du gouvernement, les annonces de celui-ci confirment nos pires craintes.\u00a0Il s&rsquo;inscrit dans la droite ligne des pr\u00e9c\u00e9dents gouvernements &#8211; \u00e0 qui l&rsquo;on doit de nombreuses r\u00e9formes d\u00e9sastreuses pour l&rsquo;ESR comme\u00a0la\u00a0loi relative aux libert\u00e9s et responsabilit\u00e9s des universit\u00e9 (LRU) en 2007 ou \u00e0 l&rsquo;automne dernier la s\u00e9lection en Master pour ne citer qu&rsquo;elles &#8211; mais va plus loin, et de mani\u00e8re plus pernicieuse. Pour \u00e9viter toute confrontation, les technocrates sont malins : ils vont pr\u00e9f\u00e9rer la tactique du salami \u00e0 l&rsquo;annonce d&rsquo;une grande r\u00e9forme \u00ab\u00a0cadre\u00a0\u00bb sur l&rsquo;enseignement sup\u00e9rieur. Ainsi, toutes ces mesures vont \u00eatre d\u00e9coup\u00e9es et \u00e9chelonn\u00e9es dans une s\u00e9rie de d\u00e9crets, d&rsquo;ordonnances et d&rsquo;appels \u00e0 projet, qui constituent un ensemble \u00e0 parfaite coh\u00e9rence lib\u00e9rale.<br \/>\n&nbsp;<br \/>\nParmi les premi\u00e8res mesures annonc\u00e9es, et que nous nous devons de combattre :<br \/>\n&#8211; l&rsquo;augmentation des frais d&rsquo;inscription pour les \u00e9tudiant-e-s extra-communautaires. Si le gouvernement a annonc\u00e9 un gel des frais d&rsquo;inscription pour les ressortissant-e-s de l&rsquo;UE, il veut faire cracher \u00e0 bassinet les \u00e9tudiant-e-s \u00e9tranger-e-s. Nous nous opposons \u00e0 cette augmentation au nom du refus de toutes formes de discrimination et au nom de la gratuit\u00e9 de l&rsquo;Enseignement Sup\u00e9rieur<br \/>\n&#8211; la mise en place d&rsquo;un syst\u00e8me de pr\u00e9requis au niveau de la L1, qui s\u2019apparente \u00e0 une s\u00e9lection d\u00e9guis\u00e9e. Alors m\u00eame que le gouvernement pr\u00e9pare aussi une r\u00e9forme du bac qui aura pour objectif de renforcer le lien entre les entreprises et le bac professionnel, il veut fermer encore plus l&rsquo;enseignement sup\u00e9rieur \u00e0 tous les lyc\u00e9en-ne-s des classes populaires et de fa\u00e7on plus large \u00e0 tou-te-s celles qui seront consid\u00e9r\u00e9s comme \u00ab\u00a0pas assez m\u00e9ritants\u00a0\u00bb. Cette s\u00e9lection est pr\u00e9vue d\u00e8s la rentr\u00e9e 2018, et prendra la forme d&rsquo;un \u00ab\u00a0contrat de r\u00e9ussite \u00e9tudiant\u00a0\u00bb, comme annonc\u00e9 par la ministre (voir la lettre adress\u00e9e aux pr\u00e9sidents d&rsquo;universit\u00e9 en pi\u00e8ce-jointe, ainsi que l&rsquo;article des \u00e9chos qui donne les orientations du gouvernement). Nous sommes contre toutes les formes de s\u00e9lection \u00e0 l&rsquo;entr\u00e9e de l&rsquo;enseignement sup\u00e9rieur, que ce soit par APB, par tirage au sort ou \u00ab\u00a0au m\u00e9rite\u00a0\u00bb.<br \/>\n&nbsp;<br \/>\n<strong>Nous r\u00e9affirmons notre attachement au principe du grade universitaire ouvrant le droit \u00e0 l&rsquo;acc\u00e8s aux cycles sup\u00e9rieurs\u00a0et notre opposition \u00e0 toutes formes de s\u00e9lections\u00a0; aussi bien \u00e0 l\u2019entr\u00e9e de la licence que dans n\u2019importe quelle autre fili\u00e8re de l\u2019Enseignement Sup\u00e9rieur. <\/strong><br \/>\n&#8211; la mise en place du Projet d&rsquo;Investissement d&rsquo;Avenir III (PIA 3 pour les intimes) qui oblige les \u00e9tablissements \u00e0 cr\u00e9er des cursus s\u00e9lectifs s&rsquo;ils veulent obtenir des financements. Ce type de financement est profond\u00e9ment in\u00e9galitaire et ne r\u00e9pond pas au besoin des \u00e9tablissements<a href=\"#_edn1\" name=\"_ednref1\">[i]<\/a>.<br \/>\n&nbsp;<br \/>\n<strong>Nous voulons que les financements se fassent sur les besoins r\u00e9els et avec comme objectif un acc\u00e8s de toutes et tous \u00e0 l&rsquo;Enseignement Sup\u00e9rieur ! <\/strong><br \/>\n&#8211; une possibilit\u00e9 accrue de changement des statuts des universit\u00e9s en \u00ab\u00a0grands \u00e9tablissements\u00a0\u00bb. Cette modification d&rsquo;apparence technique causera une plus grande opacit\u00e9 dans la gestion des \u00e9tablissements : une plus grande s\u00e9lection, un envol des frais d&rsquo;inscription et une r\u00e9duction des droits des \u00e9tudiant-e-s et personnels. Cette analyse s&rsquo;appuie sur le cas de Paris IX &#8211; Dauphine et de l&rsquo;Universit\u00e9 de Lorraine qui dans les ann\u00e9es pass\u00e9es ont obtenu ce statut. A Dauphine, cela donne des formations de licence \u00e0 7500 euros l&rsquo;ann\u00e9e ! Mme Vidal, la ministre, avait annonc\u00e9 qu&rsquo;une ordonnance serait bient\u00f4t publi\u00e9e mais, devant la bronca caus\u00e9e par cette annonce surprise, elle a d\u00e9cid\u00e9 d&rsquo;accorder un an de concertation. Le gouvernement a d\u00e9pos\u00e9 d\u00e9but juillet le projet de loi d\u2019habilitation au Conseil d\u2019\u00c9tat pour que ce dernier rende son avis.<br \/>\nMalgr\u00e9 la promesse de concertation du gouvernent la proc\u00e9dure l\u00e9gislative a d\u00e9j\u00e0 commenc\u00e9\u00a0!!! Cette disposition est particuli\u00e8rement strat\u00e9gique pour le gouvernement puisqu&rsquo;elle permet, comme pour les lois \u00ab\u00a0travail\u00a0\u00bb une inversion de la hi\u00e9rarchie des normes, notamment en mati\u00e8re de frais d&rsquo;inscription, puisque les anciennes universit\u00e9s, devenues \u00ab\u00a0grands \u00e9tablissements\u00a0\u00bb vont pouvoir les augmenter formation par formation, au fur \u00e0 mesure, sans se pr\u00e9occuper des montants fix\u00e9s nationalement. Combien de temps avant que toutes les formations soient payantes \u00e0 plusieurs milliers d&rsquo;euros, et que l&rsquo;on passe \u00e0 un syst\u00e8me d&rsquo;endettement banquier des \u00e9tudiant-es, comme au Royaume-Uni, en Afrique du Sud, au Chili&#8230;?<br \/>\n&nbsp;<br \/>\n<strong>Nous r\u00e9affirmons la n\u00e9cessit\u00e9 d&rsquo;une unification des statuts des \u00e9tablissements sous un r\u00e9gime\u00a0<\/strong><strong>statutaire permettant un enseignement libre, critique, populaire et \u00e9mancipateur !<\/strong><br \/>\nPlus globalement, <strong>nous demandons : l&rsquo;abrogation de la loi LRU de 2007, ESR de 2013 et Master de 2016, un budget r\u00e9pondant aux besoins d&rsquo;un Enseignement Sup\u00e9rieur ouvert \u00e0 tous et \u00e0 toutes, la suppression des frais d&rsquo;inscription, la suppression de toutes les fili\u00e8res s\u00e9lectives et qu&rsquo;une r\u00e9flexion soit men\u00e9e sur les cons\u00e9quences de la loi LMD de 2003.<\/strong><br \/>\nAvec la f\u00e9d\u00e9ration Sud \u00e9ducation, nous porterons nos revendications pour une \u00e9ducation \u00e9mancipatrice, de la maternelle au doctorat, et combattrons toute r\u00e9forme du baccalaur\u00e9at et de l&rsquo;enseignement sup\u00e9rieur visant \u00e0 s\u00e9parer, classer et \u00e9vincer des \u00e9l\u00e8ves et \u00e9tudiant-e-s au fil de leur scolarit\u00e9.<br \/>\n&nbsp;<br \/>\n<a href=\"http:\/\/www.solidaires-etudiant.org\/wp-content\/uploads\/2017\/09\/Communiqu\u00e9-Macron-destruction-de-lESR.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-3509\" src=\"http:\/\/www.solidaires-etudiant.org\/wp-content\/uploads\/2016\/12\/adobe-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>Solidaires \u00e9tudiant-e-s, syndicats de luttes<\/em><\/p>\n<p style=\"text-align: center;\">Porte-parolat : <em>06.86.80.24.45<\/em><\/p>\n<p style=\"text-align: center;\"><em>https:\/\/solidaires-etudiant.org\/site\/<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"mailto:contact@solidaires-etudiant-e-s.org\/site\"><em>contact@solidaires-etudiant-e-s.org\/site<\/em><\/a><\/p>\n<p><a href=\"#_ednref1\" name=\"_edn1\">[i]<\/a> Voici une analyse plus d\u00e9taill\u00e9e :\u00a0 <a href=\"https:\/\/eepso.wordpress.com\/2017\/06\/06\/forthcoming\/\">https:\/\/eepso.wordpress.com\/2017\/06\/06\/forthcoming\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00eame si cela n&rsquo;est pas une surprise au vu du programme et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[10,18],"tags":[308,467,472,538,889,1049,1050,1147],"class_list":["post-3916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques","category-esr","tag-communiques-2","tag-enseignement-superieur","tag-esr-2","tag-fioraso","tag-precarite","tag-slider","tag-slideshow","tag-universite","col-md-12"],"featured_image_src":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg","author_info":{"display_name":"Solidaires \u00e9tudiant-e-s","author_link":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit ! - Solidaires \u00e9tudiant-e-s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit ! - Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"og:description\" content=\"M\u00eame si cela n&rsquo;est pas une surprise au vu du programme et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/\" \/>\n<meta property=\"og:site_name\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-06T06:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1090\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:site\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/\"},\"author\":{\"name\":\"Solidaires \u00e9tudiant-e-s\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\"},\"headline\":\"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit !\",\"datePublished\":\"2017-09-06T06:27:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/\"},\"wordCount\":979,\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/precarite_0.jpg\",\"keywords\":[\"communiqu\u00e9s\",\"enseignement sup\u00e9rieur\",\"esr\",\"fioraso\",\"pr\u00e9carit\u00e9\",\"slider\",\"slideshow\",\"universit\u00e9\"],\"articleSection\":[\"COMMUNIQUES NATIONAUX\",\"ENSEIGNEMENT SUPERIEUR\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/\",\"name\":\"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit ! - Solidaires \u00e9tudiant-e-s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/precarite_0.jpg\",\"datePublished\":\"2017-09-06T06:27:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/precarite_0.jpg\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/precarite_0.jpg\",\"width\":1090,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2017\\\/09\\\/06\\\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"description\":\"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !\",\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"width\":1181,\"height\":827,\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/solidaires-etudiant-e-s.org\",\"https:\\\/\\\/mastodon.social\\\/@solidairesetu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_iZN9gmVAAnXbBM7wAWOag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"sameAs\":[\"https:\\\/\\\/solidaires-etudiant.org\\\/site\",\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Solidaires_tudiant-e-s\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit ! - Solidaires \u00e9tudiant-e-s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/","og_locale":"fr_FR","og_type":"article","og_title":"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit ! - Solidaires \u00e9tudiant-e-s","og_description":"M\u00eame si cela n&rsquo;est pas une surprise au vu du programme et [&hellip;]","og_url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/","og_site_name":"Solidaires \u00e9tudiant-e-s","article_publisher":"https:\/\/www.facebook.com\/solidairesetudiantes","article_author":"https:\/\/www.facebook.com\/solidairesetudiantes","article_published_time":"2017-09-06T06:27:06+00:00","og_image":[{"width":1090,"height":500,"url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg","type":"image\/jpeg"}],"author":"Solidaires \u00e9tudiant-e-s","twitter_card":"summary_large_image","twitter_creator":"@SolidairesEtu","twitter_site":"@SolidairesEtu","twitter_misc":{"\u00c9crit par":"Solidaires \u00e9tudiant-e-s","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#article","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/"},"author":{"name":"Solidaires \u00e9tudiant-e-s","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c"},"headline":"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit !","datePublished":"2017-09-06T06:27:06+00:00","mainEntityOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/"},"wordCount":979,"publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg","keywords":["communiqu\u00e9s","enseignement sup\u00e9rieur","esr","fioraso","pr\u00e9carit\u00e9","slider","slideshow","universit\u00e9"],"articleSection":["COMMUNIQUES NATIONAUX","ENSEIGNEMENT SUPERIEUR"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/","name":"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit ! - Solidaires \u00e9tudiant-e-s","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#primaryimage"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg","datePublished":"2017-09-06T06:27:06+00:00","breadcrumb":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#primaryimage","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2017\/09\/precarite_0.jpg","width":1090,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2017\/09\/06\/macron-annonce-une-destruction-de-lenseignement-superieur-public-et-gratuit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/solidaires-etudiant-e-s.org\/site\/"},{"@type":"ListItem","position":2,"name":"Macron annonce une destruction de l&#039;enseignement sup\u00e9rieur public et gratuit !"}]},{"@type":"WebSite","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","name":"Solidaires \u00e9tudiant-e-s","description":"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !","publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidaires-etudiant-e-s.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization","name":"Solidaires \u00e9tudiant-e-s","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","width":1181,"height":827,"caption":"Solidaires \u00e9tudiant-e-s"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/x.com\/SolidairesEtu","https:\/\/www.instagram.com\/solidairesetu\/","https:\/\/bsky.app\/profile\/solidaires-etudiant-e-s.org","https:\/\/mastodon.social\/@solidairesetu","https:\/\/www.youtube.com\/channel\/UC_iZN9gmVAAnXbBM7wAWOag"]},{"@type":"Person","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c","name":"Solidaires \u00e9tudiant-e-s","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","caption":"Solidaires \u00e9tudiant-e-s"},"sameAs":["https:\/\/solidaires-etudiant.org\/site","https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/www.instagram.com\/solidairesetu","https:\/\/x.com\/SolidairesEtu","https:\/\/fr.wikipedia.org\/wiki\/Solidaires_tudiant-e-s"]}]}},"_links":{"self":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/3916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/comments?post=3916"}],"version-history":[{"count":0,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/3916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media\/3912"}],"wp:attachment":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media?parent=3916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories?post=3916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/tags?post=3916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}