{"id":2905,"date":"2016-02-19T12:51:36","date_gmt":"2016-02-19T11:51:36","guid":{"rendered":"http:\/\/www.solidaires-etudiant.org\/?p=2905"},"modified":"2016-02-19T12:51:36","modified_gmt":"2016-02-19T11:51:36","slug":"masters-stop-a-lobsession-de-la-selection","status":"publish","type":"post","link":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/","title":{"rendered":"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection"},"content":{"rendered":"<p style=\"text-align: justify;\">Le conseil d\u2019\u00c9tat a r\u00e9affirm\u00e9 le 10 f\u00e9vrier l\u2019ill\u00e9galit\u00e9 de la s\u00e9lection entre la premi\u00e8re ann\u00e9e du master (M1) et la deuxi\u00e8me ann\u00e9e (M2). Cette s\u00e9lection ne serait l\u00e9gale que dans le cas o\u00f9 le master en question figurerait sur une \u00ab\u00a0liste limitative\u00a0\u00bb \u00e9tablie par d\u00e9cret, ce qui est pr\u00e9vu par l\u2019article L.612-6 du code de l\u2019\u00e9ducation. Le secr\u00e9taire d&rsquo;\u00c9tat \u00e0 l\u2019enseignement sup\u00e9rieur, Thierry Mandon, se f\u00e9licite de cette d\u00e9cision dans un communiqu\u00e9, avan\u00e7ant \u00ab\u00a0le droit de tout \u00e9tudiant \u00e0 poursuivre ses \u00e9tudes en master jusqu\u2019au terme de ce cycle\u00a0\u00bb, dans le sens d\u2019une \u00ab\u00a0s\u00e9curisation\u00a0\u00bb du \u00ab\u00a0fonctionnement actuel\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Entre les lignes se lit l\u2019orientation du gouvernement qui comme d\u2019habitude veut m\u00e9nager la ch\u00e8vre et le chou en prot\u00e9geant l\u2019ordre existant. Plusieurs sc\u00e9narios sont possibles, mais le plus probable est que nous nous dirigions vers un renforcement d\u2019un enseignement sup\u00e9rieur \u00e0 deux vitesses, avec une s\u00e9lection dans certains masters, en laissant le reste des masters \u00ab\u00a0ouverts\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ce serait une r\u00e9ponse \u00e0 l\u2019agitation au sein des enseignant-e-s dont beaucoup r\u00e9clament et d\u00e9fendent la s\u00e9lection en master. Pour nous, il s\u2019agit d\u2019un mauvais combat. Le v\u00e9ritable probl\u00e8me c\u2019est le manque de moyens\u00a0: manque de moyens pour accueillir tous les \u00e9tudiant-e-s qui souhaitent poursuivre leurs \u00e9tudes, manque de moyens pour assurer plus de cours, en petits groupes. Manque de moyens pour des formations exigeantes et de qualit\u00e9. Mais ce n\u2019est ni la responsabilit\u00e9 des \u00e9tudiant-e-s qui veulent s\u2019inscrire en master, ni la responsabilit\u00e9 des enseignant-e-s. C\u2019est la responsabilit\u00e9 des gouvernements successifs qui r\u00e9duisent les moyens des universit\u00e9s et la cr\u00e9ation de postes d\u2019enseignants-chercheurs. Le financement donn\u00e9 d\u2019une main \u00e0 travers les cr\u00e9ations de postes annonc\u00e9s par G. Fioraso ont \u00e9t\u00e9 gel\u00e9s pour combler les d\u00e9ficits cr\u00e9\u00e9s\u2026 par l\u2019argent que le gouvernement retire de l\u2019autre main en dotation globale.<\/p>\n<p>L\u2019obsession de la s\u00e9lection est un mauvais combat, car c\u2019est un combat qui se fait au nom de valeurs r\u00e9actionnaires au sens propre, de discours du genre \u00ab\u00a0le niveau baisse\u00a0\u00bb, ou encore \u00ab\u00a0master pour tout le monde, et apr\u00e8s quoi, doctorat pour tout le monde\u00a0?\u00a0\u00bb. Il y a un paradoxe \u00e0 penser que la s\u00e9lection garantit le niveau\u00a0: on sait depuis longtemps que les indicateurs utilis\u00e9s (dossiers scolaires, notes) ne permettent pas de pr\u00e9dire les progr\u00e8s futurs des \u00e9tudiant-es. Combien de fois des lyc\u00e9en-nes \u00ab\u00a0moyens\u00a0\u00bb se sont r\u00e9v\u00e9l\u00e9s d\u2019excellents \u00e9tudiant-es\u00a0? (et vice-versa). L\u2019absence de s\u00e9lection n\u2019implique pas l\u2019absence d\u2019exigence et de qualit\u00e9 dans les formations, mais cela ne peut \u00eatre obtenu qu\u2019avec des moyens humains et financiers adapt\u00e9s aux besoins, ce qui n\u2019est pas le cas aujourd\u2019hui. <strong>C\u2019est ce combat pour des moyens \u00e0 la hauteur des besoins qu\u2019il faut mener, c\u2019est le combat que m\u00e8ne la f\u00e9d\u00e9ration Solidaires \u00e9tudiant-e-s.<\/strong> Rappelons que les luttes successives pour plus de moyens au d\u00e9but des ann\u00e9es 2000 ont permis une augmentation (temporaire) du nombre de postes ouverts aux concours. Rappelons aussi que 5,5 milliards d\u2019euros d\u2019argent public partiront en 2016, comme chaque ann\u00e9e, dans une niche fiscale honteusement appel\u00e9e \u00ab\u00a0cr\u00e9dit imp\u00f4t recherche\u00a0\u00bb.<br \/>\nNous revendiquons\u00a0:<\/p>\n<ul>\n<li>L&rsquo;absence de s\u00e9lection en master et la garantie de pouvoir continuer ses \u00e9tudes dans le domaine souhait\u00e9 dans l&rsquo;universit\u00e9 souhait\u00e9e jusqu&rsquo;au M2<\/li>\n<li>Des moyens \u00e0 la hauteur des besoins dans les universit\u00e9s et le reste de l\u2019enseignement sup\u00e9rieur<\/li>\n<li>L&rsquo;harmonisation sur tout le territoire de la valeur des dipl\u00f4mes \u00a0et leur reconnaissance, contre la logique de \u00ab\u00a0l&rsquo;excellence\u00a0\u00bb et des facs plus ou moins r\u00e9put\u00e9es<\/li>\n<li>La suppression du cr\u00e9dit imp\u00f4t recherche<\/li>\n<li>La r\u00e9duction du temps de travail et de l\u2019\u00e2ge de d\u00e9part en retraite, seules mesures permettant de r\u00e9duire effectivement le ch\u00f4mage (l\u2019\u00e9cole et l\u2019universit\u00e9 n\u2019\u00e9tant pas des \u00ab\u00a0usines \u00e0 ch\u00f4meurs\u00a0\u00bb n&rsquo;ont aucune responsabilit\u00e9 \u00e0 cet \u00e9gard)<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.solidaires-etudiant.org\/wp-content\/uploads\/2016\/02\/Stop-\u00e0-lobsession-de-la-s\u00e9lection.pdf\">Communiqu\u00e9 en PDF :<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.solidaires-etudiant.org\/wp-content\/uploads\/2016\/02\/Stop-\u00e0-lobsession-de-la-s\u00e9lection.pdf\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-274\" src=\"http:\/\/www.solidaires-etudiant.org\/wp-content\/uploads\/2014\/02\/adobe-150x150.png\" alt=\"pdf\" width=\"150\" height=\"150\" srcset=\"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2014\/02\/adobe-150x150.png 150w, https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2014\/02\/adobe.png 256w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le conseil d\u2019\u00c9tat a r\u00e9affirm\u00e9 le 10 f\u00e9vrier l\u2019ill\u00e9galit\u00e9 de la s\u00e9lection [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[10,15,18],"tags":[231,417,431,743,764,1049],"class_list":["post-2905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques","category-droits-etudiants","category-esr","tag-budgets","tag-doctorat","tag-droits","tag-m1","tag-master","tag-slider","col-md-12"],"featured_image_src":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg","author_info":{"display_name":"Solidaires \u00e9tudiant-e-s","author_link":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection - Solidaires \u00e9tudiant-e-s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection - Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"og:description\" content=\"Le conseil d\u2019\u00c9tat a r\u00e9affirm\u00e9 le 10 f\u00e9vrier l\u2019ill\u00e9galit\u00e9 de la s\u00e9lection [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/\" \/>\n<meta property=\"og:site_name\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-19T11:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"322\" \/>\n\t<meta property=\"og:image:height\" content=\"292\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:site\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/\"},\"author\":{\"name\":\"Solidaires \u00e9tudiant-e-s\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\"},\"headline\":\"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection\",\"datePublished\":\"2016-02-19T11:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/\"},\"wordCount\":721,\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Master.jpg\",\"keywords\":[\"budgets\",\"doctorat\",\"droits\",\"M1\",\"master\",\"slider\"],\"articleSection\":[\"COMMUNIQUES NATIONAUX\",\"DROITS ETUDIANTS\",\"ENSEIGNEMENT SUPERIEUR\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/\",\"name\":\"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection - Solidaires \u00e9tudiant-e-s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Master.jpg\",\"datePublished\":\"2016-02-19T11:51:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Master.jpg\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Master.jpg\",\"width\":322,\"height\":292},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2016\\\/02\\\/19\\\/masters-stop-a-lobsession-de-la-selection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"description\":\"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !\",\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"width\":1181,\"height\":827,\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/solidaires-etudiant-e-s.org\",\"https:\\\/\\\/mastodon.social\\\/@solidairesetu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_iZN9gmVAAnXbBM7wAWOag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"sameAs\":[\"https:\\\/\\\/solidaires-etudiant.org\\\/site\",\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Solidaires_tudiant-e-s\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection - Solidaires \u00e9tudiant-e-s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/","og_locale":"fr_FR","og_type":"article","og_title":"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection - Solidaires \u00e9tudiant-e-s","og_description":"Le conseil d\u2019\u00c9tat a r\u00e9affirm\u00e9 le 10 f\u00e9vrier l\u2019ill\u00e9galit\u00e9 de la s\u00e9lection [&hellip;]","og_url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/","og_site_name":"Solidaires \u00e9tudiant-e-s","article_publisher":"https:\/\/www.facebook.com\/solidairesetudiantes","article_author":"https:\/\/www.facebook.com\/solidairesetudiantes","article_published_time":"2016-02-19T11:51:36+00:00","og_image":[{"width":322,"height":292,"url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg","type":"image\/jpeg"}],"author":"Solidaires \u00e9tudiant-e-s","twitter_card":"summary_large_image","twitter_creator":"@SolidairesEtu","twitter_site":"@SolidairesEtu","twitter_misc":{"\u00c9crit par":"Solidaires \u00e9tudiant-e-s","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#article","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/"},"author":{"name":"Solidaires \u00e9tudiant-e-s","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c"},"headline":"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection","datePublished":"2016-02-19T11:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/"},"wordCount":721,"publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg","keywords":["budgets","doctorat","droits","M1","master","slider"],"articleSection":["COMMUNIQUES NATIONAUX","DROITS ETUDIANTS","ENSEIGNEMENT SUPERIEUR"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/","name":"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection - Solidaires \u00e9tudiant-e-s","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#primaryimage"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg","datePublished":"2016-02-19T11:51:36+00:00","breadcrumb":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#primaryimage","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2016\/02\/Master.jpg","width":322,"height":292},{"@type":"BreadcrumbList","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2016\/02\/19\/masters-stop-a-lobsession-de-la-selection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/solidaires-etudiant-e-s.org\/site\/"},{"@type":"ListItem","position":2,"name":"Masters\u00a0: Stop \u00e0 l\u2019obsession de la s\u00e9lection"}]},{"@type":"WebSite","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","name":"Solidaires \u00e9tudiant-e-s","description":"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !","publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidaires-etudiant-e-s.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization","name":"Solidaires \u00e9tudiant-e-s","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","width":1181,"height":827,"caption":"Solidaires \u00e9tudiant-e-s"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/x.com\/SolidairesEtu","https:\/\/www.instagram.com\/solidairesetu\/","https:\/\/bsky.app\/profile\/solidaires-etudiant-e-s.org","https:\/\/mastodon.social\/@solidairesetu","https:\/\/www.youtube.com\/channel\/UC_iZN9gmVAAnXbBM7wAWOag"]},{"@type":"Person","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c","name":"Solidaires \u00e9tudiant-e-s","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","caption":"Solidaires \u00e9tudiant-e-s"},"sameAs":["https:\/\/solidaires-etudiant.org\/site","https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/www.instagram.com\/solidairesetu","https:\/\/x.com\/SolidairesEtu","https:\/\/fr.wikipedia.org\/wiki\/Solidaires_tudiant-e-s"]}]}},"_links":{"self":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/2905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/comments?post=2905"}],"version-history":[{"count":0,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/2905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media\/2906"}],"wp:attachment":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media?parent=2905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories?post=2905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/tags?post=2905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}