{"id":2557,"date":"2015-10-02T16:15:20","date_gmt":"2015-10-02T14:15:20","guid":{"rendered":"http:\/\/www.solidaires-etudiant.org\/?p=2557"},"modified":"2015-10-02T16:15:20","modified_gmt":"2015-10-02T14:15:20","slug":"guide-de-letudiant-e-solidaires-2015-2016","status":"publish","type":"post","link":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/","title":{"rendered":"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016"},"content":{"rendered":"<p>Nous l&rsquo;attendions depuis des mois, oui, oui le voil\u00e0 le guide de l&rsquo;\u00e9tudiant-e solidaires 2015-2016 !<br \/>\nMis \u00e0 jour, rectifi\u00e9 et r\u00e9\u00e9crit par rapport \u00e0 l&rsquo;an dernier.<br \/>\nCliquez sur l&rsquo;image pour le consulter :<br \/>\n&nbsp;<br \/>\n<a href=\"http:\/\/www.calameo.com\/read\/0045118879c760efc932d\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2558\" src=\"http:\/\/www.solidaires-etudiant.org\/wp-content\/uploads\/2015\/10\/gui2015-page001.png\" alt=\"gui2015-page001\" width=\"419\" height=\"595\" srcset=\"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png 419w, https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001-211x300.png 211w\" sizes=\"auto, (max-width: 419px) 100vw, 419px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous l&rsquo;attendions depuis des mois, oui, oui le voil\u00e0 le guide de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[15],"tags":[1049],"class_list":["post-2557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-droits-etudiants","tag-slider","col-md-12"],"featured_image_src":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png","author_info":{"display_name":"Solidaires \u00e9tudiant-e-s","author_link":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016 - Solidaires \u00e9tudiant-e-s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016 - Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"og:description\" content=\"Nous l&rsquo;attendions depuis des mois, oui, oui le voil\u00e0 le guide de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/solidairesetudiantes\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-02T14:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png\" \/>\n\t<meta property=\"og:image:width\" content=\"419\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:site\" content=\"@SolidairesEtu\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/\"},\"author\":{\"name\":\"Solidaires \u00e9tudiant-e-s\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\"},\"headline\":\"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016\",\"datePublished\":\"2015-10-02T14:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/\"},\"wordCount\":42,\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gui2015-page001.png\",\"keywords\":[\"slider\"],\"articleSection\":[\"DROITS ETUDIANTS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/\",\"name\":\"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016 - Solidaires \u00e9tudiant-e-s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gui2015-page001.png\",\"datePublished\":\"2015-10-02T14:15:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gui2015-page001.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/gui2015-page001.png\",\"width\":419,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/2015\\\/10\\\/02\\\/guide-de-letudiant-e-solidaires-2015-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"description\":\"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !\",\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"width\":1181,\"height\":827,\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/solidaires-etudiant-e-s.org\",\"https:\\\/\\\/mastodon.social\\\/@solidairesetu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_iZN9gmVAAnXbBM7wAWOag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/person\\\/0efb3e0ff4e2f12b5a5abcd4352aa86c\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-SESL-rond-512-96x96.png\",\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"sameAs\":[\"https:\\\/\\\/solidaires-etudiant.org\\\/site\",\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Solidaires_tudiant-e-s\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016 - Solidaires \u00e9tudiant-e-s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/","og_locale":"fr_FR","og_type":"article","og_title":"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016 - Solidaires \u00e9tudiant-e-s","og_description":"Nous l&rsquo;attendions depuis des mois, oui, oui le voil\u00e0 le guide de [&hellip;]","og_url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/","og_site_name":"Solidaires \u00e9tudiant-e-s","article_publisher":"https:\/\/www.facebook.com\/solidairesetudiantes","article_author":"https:\/\/www.facebook.com\/solidairesetudiantes","article_published_time":"2015-10-02T14:15:20+00:00","og_image":[{"width":419,"height":595,"url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png","type":"image\/png"}],"author":"Solidaires \u00e9tudiant-e-s","twitter_card":"summary_large_image","twitter_creator":"@SolidairesEtu","twitter_site":"@SolidairesEtu","twitter_misc":{"\u00c9crit par":"Solidaires \u00e9tudiant-e-s"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#article","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/"},"author":{"name":"Solidaires \u00e9tudiant-e-s","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c"},"headline":"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016","datePublished":"2015-10-02T14:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/"},"wordCount":42,"publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png","keywords":["slider"],"articleSection":["DROITS ETUDIANTS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/","name":"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016 - Solidaires \u00e9tudiant-e-s","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#primaryimage"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png","datePublished":"2015-10-02T14:15:20+00:00","breadcrumb":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#primaryimage","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2015\/10\/gui2015-page001.png","width":419,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/2015\/10\/02\/guide-de-letudiant-e-solidaires-2015-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/solidaires-etudiant-e-s.org\/site\/"},{"@type":"ListItem","position":2,"name":"Guide de l&#039;\u00e9tudiant-e solidaires 2015-2016"}]},{"@type":"WebSite","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","name":"Solidaires \u00e9tudiant-e-s","description":"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !","publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidaires-etudiant-e-s.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization","name":"Solidaires \u00e9tudiant-e-s","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","width":1181,"height":827,"caption":"Solidaires \u00e9tudiant-e-s"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/x.com\/SolidairesEtu","https:\/\/www.instagram.com\/solidairesetu\/","https:\/\/bsky.app\/profile\/solidaires-etudiant-e-s.org","https:\/\/mastodon.social\/@solidairesetu","https:\/\/www.youtube.com\/channel\/UC_iZN9gmVAAnXbBM7wAWOag"]},{"@type":"Person","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/person\/0efb3e0ff4e2f12b5a5abcd4352aa86c","name":"Solidaires \u00e9tudiant-e-s","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2020\/01\/logo-SESL-rond-512-96x96.png","caption":"Solidaires \u00e9tudiant-e-s"},"sameAs":["https:\/\/solidaires-etudiant.org\/site","https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/www.instagram.com\/solidairesetu","https:\/\/x.com\/SolidairesEtu","https:\/\/fr.wikipedia.org\/wiki\/Solidaires_tudiant-e-s"]}]}},"_links":{"self":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":0,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts\/2557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media\/2558"}],"wp:attachment":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/media?parent=2557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories?post=2557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/tags?post=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}