{"id":1232,"count":2,"description":"","link":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/","name":"TOURS","slug":"tours","taxonomy":"category","parent":23,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des TOURS - Solidaires \u00e9tudiant-e-s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des TOURS - Solidaires \u00e9tudiant-e-s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/\" \/>\n<meta property=\"og:site_name\" content=\"Solidaires \u00e9tudiant-e-s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SolidairesEtu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/category\\\/actus-locales\\\/tours\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/category\\\/actus-locales\\\/tours\\\/\",\"name\":\"Archives des TOURS - Solidaires \u00e9tudiant-e-s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/category\\\/actus-locales\\\/tours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/category\\\/actus-locales\\\/tours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACTUS LOCALES\",\"item\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/category\\\/actus-locales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TOURS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"description\":\"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !\",\"publisher\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#organization\",\"name\":\"Solidaires \u00e9tudiant-e-s\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"contentUrl\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13-1.png\",\"width\":1181,\"height\":827,\"caption\":\"Solidaires \u00e9tudiant-e-s\"},\"image\":{\"@id\":\"https:\\\/\\\/solidaires-etudiant-e-s.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solidairesetudiantes\",\"https:\\\/\\\/x.com\\\/SolidairesEtu\",\"https:\\\/\\\/www.instagram.com\\\/solidairesetu\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/solidaires-etudiant-e-s.org\",\"https:\\\/\\\/mastodon.social\\\/@solidairesetu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC_iZN9gmVAAnXbBM7wAWOag\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des TOURS - Solidaires \u00e9tudiant-e-s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des TOURS - Solidaires \u00e9tudiant-e-s","og_url":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/","og_site_name":"Solidaires \u00e9tudiant-e-s","twitter_card":"summary_large_image","twitter_site":"@SolidairesEtu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/","name":"Archives des TOURS - Solidaires \u00e9tudiant-e-s","isPartOf":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website"},"breadcrumb":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/tours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/solidaires-etudiant-e-s.org\/site\/"},{"@type":"ListItem","position":2,"name":"ACTUS LOCALES","item":"https:\/\/solidaires-etudiant-e-s.org\/site\/category\/actus-locales\/"},{"@type":"ListItem","position":3,"name":"TOURS"}]},{"@type":"WebSite","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#website","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","name":"Solidaires \u00e9tudiant-e-s","description":"Syndicats pour un enseignement sup\u00e9rieur gratuit, ouvert, et \u00e9mancipateur !","publisher":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidaires-etudiant-e-s.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#organization","name":"Solidaires \u00e9tudiant-e-s","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","contentUrl":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-content\/uploads\/2025\/12\/13-1.png","width":1181,"height":827,"caption":"Solidaires \u00e9tudiant-e-s"},"image":{"@id":"https:\/\/solidaires-etudiant-e-s.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solidairesetudiantes","https:\/\/x.com\/SolidairesEtu","https:\/\/www.instagram.com\/solidairesetu\/","https:\/\/bsky.app\/profile\/solidaires-etudiant-e-s.org","https:\/\/mastodon.social\/@solidairesetu","https:\/\/www.youtube.com\/channel\/UC_iZN9gmVAAnXbBM7wAWOag"]}]}},"_links":{"self":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories\/1232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/categories\/23"}],"wp:post_type":[{"href":"https:\/\/solidaires-etudiant-e-s.org\/site\/wp-json\/wp\/v2\/posts?categories=1232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}